{"id":77,"count":1,"description":"","link":"https:\/\/publikationer.dk\/index.php\/tag\/tubu\/","name":"TUBU","slug":"tubu","taxonomy":"post_tag","meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/publikationer.dk\/index.php\/tag\/tubu\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/publikationer.dk\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/77\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/publikationer.dk#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/publikationer.dk\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/publikationer.dk\\\/index.php\\\/tag\\\/tubu\\\/#listItem\",\"name\":\"TUBU\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/publikationer.dk\\\/index.php\\\/tag\\\/tubu\\\/#listItem\",\"position\":2,\"name\":\"TUBU\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/publikationer.dk#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/publikationer.dk\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/77\\\/#collectionpage\",\"url\":\"https:\\\/\\\/publikationer.dk\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/77\\\/\",\"name\":\"TUBU | Publikationer.dk\",\"inLanguage\":\"da-DK\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/publikationer.dk\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/publikationer.dk\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/77\\\/#breadcrumblist\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/publikationer.dk\\\/#organization\",\"name\":\"A-Z FOTOS og Konsulentvirksomhed\",\"url\":\"https:\\\/\\\/publikationer.dk\\\/\",\"telephone\":\"+4525326588\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/publikationer.dk\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Soeren-Breiting-foto.jpg?fit=970%2C970&ssl=1\",\"@id\":\"https:\\\/\\\/publikationer.dk\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/77\\\/#organizationLogo\",\"width\":970,\"height\":970,\"caption\":\"P\\u00e6dagogisk forsker,  konsulent, biolog, naturformidler og forfatter S\\u00f8ren Breiting\"},\"image\":{\"@id\":\"https:\\\/\\\/publikationer.dk\\\/wp-json\\\/wp\\\/v2\\\/tags\\\/77\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soren.breiting\",\"https:\\\/\\\/twitter.com\\\/soerenbreiting?lang=en\",\"https:\\\/\\\/www.instagram.com\\\/breitingsoren\\\/\",\"https:\\\/\\\/dk.linkedin.com\\\/in\\\/sorenbreiting\"]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/publikationer.dk\\\/#website\",\"url\":\"https:\\\/\\\/publikationer.dk\\\/\",\"name\":\"Publikationer.dk\",\"inLanguage\":\"da-DK\",\"publisher\":{\"@id\":\"https:\\\/\\\/publikationer.dk\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"TUBU | Publikationer.dk","description":"","canonical_url":"https:\/\/publikationer.dk\/index.php\/tag\/tubu\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/publikationer.dk\/wp-json\/wp\/v2\/tags\/77\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/publikationer.dk#listItem","position":1,"name":"Home","item":"https:\/\/publikationer.dk","nextItem":{"@type":"ListItem","@id":"https:\/\/publikationer.dk\/index.php\/tag\/tubu\/#listItem","name":"TUBU"}},{"@type":"ListItem","@id":"https:\/\/publikationer.dk\/index.php\/tag\/tubu\/#listItem","position":2,"name":"TUBU","previousItem":{"@type":"ListItem","@id":"https:\/\/publikationer.dk#listItem","name":"Home"}}]},{"@type":"CollectionPage","@id":"https:\/\/publikationer.dk\/wp-json\/wp\/v2\/tags\/77\/#collectionpage","url":"https:\/\/publikationer.dk\/wp-json\/wp\/v2\/tags\/77\/","name":"TUBU | Publikationer.dk","inLanguage":"da-DK","isPartOf":{"@id":"https:\/\/publikationer.dk\/#website"},"breadcrumb":{"@id":"https:\/\/publikationer.dk\/wp-json\/wp\/v2\/tags\/77\/#breadcrumblist"}},{"@type":"Organization","@id":"https:\/\/publikationer.dk\/#organization","name":"A-Z FOTOS og Konsulentvirksomhed","url":"https:\/\/publikationer.dk\/","telephone":"+4525326588","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/publikationer.dk\/wp-content\/uploads\/2021\/02\/Soeren-Breiting-foto.jpg?fit=970%2C970&ssl=1","@id":"https:\/\/publikationer.dk\/wp-json\/wp\/v2\/tags\/77\/#organizationLogo","width":970,"height":970,"caption":"P\u00e6dagogisk forsker,  konsulent, biolog, naturformidler og forfatter S\u00f8ren Breiting"},"image":{"@id":"https:\/\/publikationer.dk\/wp-json\/wp\/v2\/tags\/77\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/soren.breiting","https:\/\/twitter.com\/soerenbreiting?lang=en","https:\/\/www.instagram.com\/breitingsoren\/","https:\/\/dk.linkedin.com\/in\/sorenbreiting"]},{"@type":"WebSite","@id":"https:\/\/publikationer.dk\/#website","url":"https:\/\/publikationer.dk\/","name":"Publikationer.dk","inLanguage":"da-DK","publisher":{"@id":"https:\/\/publikationer.dk\/#organization"}}]}},"_links":{"self":[{"href":"https:\/\/publikationer.dk\/index.php\/wp-json\/wp\/v2\/tags\/77","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/publikationer.dk\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/publikationer.dk\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/publikationer.dk\/index.php\/wp-json\/wp\/v2\/posts?tags=77"},{"href":"https:\/\/publikationer.dk\/index.php\/wp-json\/wp\/v2\/pmb_content?tags=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}